{"id":67795,"date":"2017-05-02T00:56:23","date_gmt":"2017-05-02T00:56:23","guid":{"rendered":"https:\/\/wordpress.org\/plugins\/oll-cielo-checkout\/"},"modified":"2017-05-02T00:56:23","modified_gmt":"2017-05-02T00:56:23","slug":"oll-cielo-checkout","status":"publish","type":"plugin","link":"https:\/\/pan.wordpress.org\/plugins\/oll-cielo-checkout\/","author":14901613,"comment_status":"closed","ping_status":"closed","template":"","meta":{"version":"1.0","stable_tag":"trunk","tested":"4.7.35","requires":"3.0.1","requires_php":"","requires_plugins":"","header_name":"OLL Cielo Checkout","header_author":"Orlando Lacerda","header_description":"(vers\u00e3o gratuita) Um plugin extremamente simples e direto com foco no resultado. O plugin foi desenvolvido para funcionar independente de plataformas WooCommerce e afins, o que te liberta para adapt\u00e1-lo a suas necessidades. Incluso, cadastro de produtos e servi\u00e7os.","assets_banners_color":"ffffff","last_updated":"2017-05-02 00:56:23","external_support_url":"","external_repository_url":"","donate_link":"http:\/\/orlandolacerda.com\/","header_plugin_uri":"http:\/\/orlandolacerda.com\/plugins\/cielo-checkout","header_author_uri":"http:\/\/orlandolacerda.com","rating":0,"author_block_rating":0,"active_installs":10,"downloads":2345,"num_ratings":0,"support_threads":0,"support_threads_resolved":0,"author_block_count":0,"sections":["description","installation","faq"],"tags":[],"upgrade_notice":[],"ratings":{"1":0,"2":0,"3":0,"4":0,"5":0},"assets_icons":{"icon-128x128.png":{"filename":"icon-128x128.png","revision":"1649291","resolution":"128x128","location":"assets","width":128,"height":128},"icon-256x256.png":{"filename":"icon-256x256.png","revision":"1649291","resolution":"256x256","location":"assets","width":256,"height":256}},"assets_banners":{"banner-772x25.png":{"filename":"banner-772x25.png","revision":"1649291","resolution":"772x25","location":"assets","width":772,"height":250}},"assets_blueprints":{},"all_blocks":[],"tagged_versions":[],"block_files":[],"assets_screenshots":{"screenshot-1.png":{"filename":"screenshot-1.png","revision":"1649291","resolution":"1","location":"assets","width":1354,"height":583},"screenshot-2.png":{"filename":"screenshot-2.png","revision":"1649291","resolution":"2","location":"assets","width":1351,"height":602},"screenshot-3.png":{"filename":"screenshot-3.png","revision":"1649291","resolution":"3","location":"assets","width":1195,"height":562},"screenshot-4.png":{"filename":"screenshot-4.png","revision":"1649291","resolution":"4","location":"assets","width":346,"height":123},"screenshot-5.png":{"filename":"screenshot-5.png","revision":"1649291","resolution":"5","location":"assets","width":1350,"height":675}},"screenshots":{"1":"Acesse atrav\u00e9s do Painel Administrativo do Wordpress","2":"Cadastre uma ou mais filiais para a integra\u00e7\u00e3o de acordo com sua necessidade","3":"Cadastre produto e servi\u00e7os de forma simples e eficiente","4":"Inclua o c\u00f3digo shortcode de acordo como sugerido no guia de instala\u00e7\u00e3o, informe o c\u00f3digo do produto a ser faturado","5":"O Cliente clicar\u00e1 no bot\u00e3o e pronto! um modal animado com a tela de pagamento ser\u00e1 aberto."}},"plugin_section":[],"plugin_tags":[3148,17525,140432,11475,1887],"plugin_category":[45],"plugin_contributors":[140433],"plugin_business_model":[],"class_list":["post-67795","plugin","type-plugin","status-publish","hentry","plugin_tags-checkout","plugin_tags-cielo","plugin_tags-cielo-checkout","plugin_tags-credit-card","plugin_tags-payments","plugin_category-ecommerce","plugin_contributors-orlandolac","plugin_committers-orlandolac"],"banners":[],"icons":{"svg":false,"icon":"https:\/\/ps.w.org\/oll-cielo-checkout\/assets\/icon-128x128.png?rev=1649291","icon_2x":"https:\/\/ps.w.org\/oll-cielo-checkout\/assets\/icon-256x256.png?rev=1649291","generated":false},"screenshots":[{"src":"https:\/\/ps.w.org\/oll-cielo-checkout\/assets\/screenshot-1.png?rev=1649291","caption":"Acesse atrav\u00e9s do Painel Administrativo do Wordpress"},{"src":"https:\/\/ps.w.org\/oll-cielo-checkout\/assets\/screenshot-2.png?rev=1649291","caption":"Cadastre uma ou mais filiais para a integra\u00e7\u00e3o de acordo com sua necessidade"},{"src":"https:\/\/ps.w.org\/oll-cielo-checkout\/assets\/screenshot-3.png?rev=1649291","caption":"Cadastre produto e servi\u00e7os de forma simples e eficiente"},{"src":"https:\/\/ps.w.org\/oll-cielo-checkout\/assets\/screenshot-4.png?rev=1649291","caption":"Inclua o c\u00f3digo shortcode de acordo como sugerido no guia de instala\u00e7\u00e3o, informe o c\u00f3digo do produto a ser faturado"},{"src":"https:\/\/ps.w.org\/oll-cielo-checkout\/assets\/screenshot-5.png?rev=1649291","caption":"O Cliente clicar\u00e1 no bot\u00e3o e pronto! um modal animado com a tela de pagamento ser\u00e1 aberto."}],"raw_content":"<!--section=description-->\n<p>Vers\u00e3o Gratuita<\/p>\n\n<ul>\n<li><p>Requer o plugin Advanced Custom Fields PRO\nUm plugin extremamente simples e direto com foco no resultado. O plugin foi desenvolvido para funcionar independente de plataformas WooCommerce e afins, o que te liberta para adapt\u00e1-lo a suas necessidades. Incluso, cadastro de produtos e servi\u00e7os.<\/p><\/li>\n<li><p>Cadastro de Produtos e Servi\u00e7os (Produtos Digitais e Servi\u00e7os, Retirada na Loja)<\/p><\/li>\n<li>Modo de Entrega Desativado\n\n<ul>\n<li>(quando desativado) Sem cobran\u00e7a de frete (aplic\u00e1vel para servi\u00e7os e produtos digitais).<\/li>\n<\/ul><\/li>\n<li>Suporta M\u00faltiplas Contas Cielo\n\n<ul>\n<li>Pode ser utilizada a mesma integra\u00e7\u00e3o para empresas distintas, como em filiais por exemplo.<\/li>\n<\/ul><\/li>\n<li>Altera\u00e7\u00e3o do texto do bot\u00e3o atrav\u00e9s do shortcode<\/li>\n<\/ul>\n\n<p>Vers\u00e3o PRO<\/p>\n\n<ul>\n<li>Todas as op\u00e7\u00f5es da vers\u00e3o gratuita<\/li>\n<li>Cadastro de Produtos e Servi\u00e7os (Material F\u00edsico, Produtos Digitais e Servi\u00e7os)<\/li>\n<li>Aplicar Desconto por Tipo (Porcentagem, fixa)<\/li>\n<li>Aplicar Desconto por Met\u00f3do de Pagamento (Boleto, Cart\u00e3\u00f3 de D\u00e9bito)<\/li>\n<li>Ativar\/Desativar Modo de Entrega \n\n<ul>\n<li>Correios (\u00c9 necess\u00e1rio uma configura\u00e7\u00e3o pr\u00e9via no Backoffice Cielo.)<\/li>\n<li>Frete com Valor Fixo<\/li>\n<li>Frete Gr\u00e1tis<\/li>\n<li>Retirada na Loja<\/li>\n<li>(quando desativado) Sem cobran\u00e7a de frete (aplic\u00e1vel para servi\u00e7os e produtos digitais).<\/li>\n<\/ul><\/li>\n<li>Ativar\/Desativar modo Antifraude (Prote\u00e7\u00e3o contra fraude, chargeback)<\/li>\n<li>Ativar\/Desativar Pagamento Recorrente \n\n<ul>\n<li>Mensal, Bimestral, Trimestral, Semestral ou Anual e Quantidade m\u00e1xima de cobran\u00e7as<\/li>\n<\/ul><\/li>\n<li>Altera\u00e7\u00e3o da cor do modal atrav\u00e9s do shortcode<\/li>\n<\/ul>\n\n<!--section=installation-->\n<p>Esta sess\u00e3o descreve os requ\u00edsitos e como instalar o plugin.<\/p>\n\n<p>IMPORTANTE:\nEste plugin requer o plugin Advanced Custom Fields PRO instalado<\/p>\n\n<ol>\n<li>Envie a pasta do plugin  para o diret\u00f3rio <code>\/wp-content\/plugins\/<\/code><\/li>\n<li>Ative o plugin atrav\u00e9s da aba 'Plugins' na Administra\u00e7\u00e3o<\/li>\n<li>Clique no novo menu \"Cielo\" e depois em \"filiais\"<\/li>\n<li>Crie uma filial e insira o MerchantId (C\u00f3digo Informado pela Cielo)<\/li>\n<li>Crie um novo produto em Cielo - Adicionar Novo<\/li>\n<li>Inclua o c\u00f3digo ...php do_action('[cielo-checkout-oll id='{codigo_pagamento}']'); ?&gt; em seu template\n\n<ul>\n<li>Substitua o {codigo_pagamento} pelo id de seu post cielo.<\/li>\n<li>Voc\u00ea tamb\u00e9m pode informar o parametro label no shortcode para mudar o t\u00edtulo do bot\u00e3o, exemplo (label=\"Comprar\")<\/li>\n<\/ul><\/li>\n<\/ol>\n\n<!--section=faq-->\n<dl>\n<dt>Installation Instructions<\/dt>\n<dd><p>Esta sess\u00e3o descreve os requ\u00edsitos e como instalar o plugin.<\/p>\n\n<p>IMPORTANTE:\nEste plugin requer o plugin Advanced Custom Fields PRO instalado<\/p>\n\n<ol>\n<li>Envie a pasta do plugin  para o diret\u00f3rio <code>\/wp-content\/plugins\/<\/code><\/li>\n<li>Ative o plugin atrav\u00e9s da aba 'Plugins' na Administra\u00e7\u00e3o<\/li>\n<li>Clique no novo menu \"Cielo\" e depois em \"filiais\"<\/li>\n<li>Crie uma filial e insira o MerchantId (C\u00f3digo Informado pela Cielo)<\/li>\n<li>Crie um novo produto em Cielo - Adicionar Novo<\/li>\n<li>Inclua o c\u00f3digo ...php do_action('[cielo-checkout-oll id='{codigo_pagamento}']'); ?&gt; em seu template\n\n<ul>\n<li>Substitua o {codigo_pagamento} pelo id de seu post cielo.<\/li>\n<li>Voc\u00ea tamb\u00e9m pode informar o parametro label no shortcode para mudar o t\u00edtulo do bot\u00e3o, exemplo (label=\"Comprar\")<\/li>\n<\/ul><\/li>\n<\/ol><\/dd>\n<dt>O plugin cria algum menu na interface administrativa?<\/dt>\n<dd><p>Sim. O menu possu\u00ed um \u00edcone de \"olhinho\" juntamente com o nome \"Cielo\".<\/p><\/dd>\n<dt>\u00c9 necess\u00e1rio conhecimento t\u00e9cnico para utilizar este plugin?<\/dt>\n<dd><p>Definitivamente n\u00e3o. Qualquer pessoa que leia bem a documenta\u00e7\u00e3o conseguir\u00e1 utilizar este plugin com bastante facilidade, se atente ao conte\u00fado e dicas de instala\u00e7\u00e3o e voc\u00ea ter\u00e1 o resultado que espera.<\/p><\/dd>\n<dt>Quanto custa a vers\u00e3o PRO e como fa\u00e7o para adquiri-la ?<\/dt>\n<dd><p>Quando voc\u00ea compra um plugin voc\u00ea n\u00e3o s\u00f3 estar\u00e1 ajudando a manter o projeto ativo e atualizado como tamb\u00e9m recebe suporte eficiente para seu neg\u00f3cio. A vers\u00e3o PRO \u00e9 vital\u00edcia e voc\u00ea poder\u00e1 utilizar em seus projetos. (Pre\u00e7o R$ 129,90) Voc\u00ea n\u00e3o est\u00e1 autorizado a revende-la.<\/p><\/dd>\n<dt>Requer Advanced Custom Fields PRO<\/dt>\n<dd><p>Sim. Voc\u00ea precisar\u00e1 da vers\u00e3o PRO do plugin Advanced Custom Fields para usar este plugin.<\/p><\/dd>\n<dt>Quantos shortcode do plugin posso colocar em uma p\u00e1gina?<\/dt>\n<dd><p>O plugin apenas suporta um \u00fanico bot\u00e3o por p\u00e1gina. Voc\u00ea pode ter bot\u00f5es ilimitados desde que seja em p\u00e1ginas distintas.<\/p><\/dd>\n<dt>Aonde \u00e9 inserido o c\u00f3digo da integra\u00e7\u00e3o da Cielo?<\/dt>\n<dd><p>O c\u00f3digo chamado de \"MerchantId\" pela Cielo, \u00e9 o seu c\u00f3digo \u00fanico da loja. Voc\u00ea poder\u00e1 incluir c\u00f3digos ilimitados de lojas distintas na p\u00e1gina de Filial do Plugin.<\/p><\/dd>\n<dt>Como \u00e9 cadastrado os produtos e servi\u00e7os ?<\/dt>\n<dd><p>Atrav\u00e9s do menu \"Cielo\" presente na administra\u00e7\u00e3o do Wordpress, l\u00e1 voc\u00ea poder\u00e1 especificar quais os produtos\/servi\u00e7os que est\u00e3o sendo cobrados, Especificar o nome, valor, quantidade e um c\u00f3digo pr\u00f3prio (sku).<\/p><\/dd>\n\n<\/dl>","raw_excerpt":"Um plugin extremamente simples e direto com foco no resultado e independente de plataformas.","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin\/67795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin"}],"about":[{"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/types\/plugin"}],"replies":[{"embeddable":true,"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/comments?post=67795"}],"author":[{"embeddable":true,"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wporg\/v1\/users\/orlandolac"}],"wp:attachment":[{"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/media?parent=67795"}],"wp:term":[{"taxonomy":"plugin_section","embeddable":true,"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_section?post=67795"},{"taxonomy":"plugin_tags","embeddable":true,"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_tags?post=67795"},{"taxonomy":"plugin_category","embeddable":true,"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_category?post=67795"},{"taxonomy":"plugin_contributors","embeddable":true,"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_contributors?post=67795"},{"taxonomy":"plugin_business_model","embeddable":true,"href":"https:\/\/pan.wordpress.org\/plugins\/wp-json\/wp\/v2\/plugin_business_model?post=67795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}